{"id":14681,"date":"2024-02-04T11:19:44","date_gmt":"2024-02-04T07:49:44","guid":{"rendered":"https:\/\/www.itpiran.net\/blog\/?p=14681"},"modified":"2024-02-04T12:59:18","modified_gmt":"2024-02-04T09:29:18","slug":"how-to-use-find-and-locate-to-search-for-files-on-linuxsize","status":"publish","type":"post","link":"https:\/\/www.itpiran.net\/blog\/de\/tutorials\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\/","title":{"rendered":"Wie man mit \u201eFinden\u201c und \u201eLocaten\u201c in Linux nach Dateien sucht"},"content":{"rendered":"<h2 id=\"%d9%85%d9%82%d8%af%d9%85%d9%87\">Einf\u00fchrung<\/h2>\n<p>Eines der Probleme, mit denen Linux-Einsteiger konfrontiert werden, ist das Auffinden der gesuchten Dateien. Diese Anleitung zeigt Ihnen die Verwendung des Befehls. <code>finden<\/code> Es enth\u00e4lt den korrekten Namen. Es hilft Ihnen, mithilfe verschiedener Filter und Parameter nach Dateien auf Ihrem System zu suchen. Au\u00dferdem beschreibt es kurz den Befehl. <code>lokalisieren<\/code> die dazu genutzt werden k\u00f6nnen, Dateien auf eine andere Art und Weise zu suchen.<\/p>\n<h5 id=\"%d9%be%db%8c%d8%b4-%d9%86%db%8c%d8%a7%d8%b2-%d9%87%d8%a7\">Voraussetzungen<\/h5>\n<ul>\n<li>Um dieser Anleitung zu folgen, ben\u00f6tigen Sie Zugriff auf einen Computer mit einem Linux-basierten Betriebssystem. Dies kann ein virtueller privater Server (VPS) sein, mit dem Sie sich per SSH verbinden, oder Ihr lokaler Rechner. Dieses Tutorial wurde zwar mit einem Linux-Server unter Ubuntu 20.04 getestet, die Beispiele sollten aber auf jedem Computer mit jeder beliebigen Linux-Distribution funktionieren.<\/li>\n<\/ul>\n<h2 id=\"%d9%be%db%8c%d8%af%d8%a7-%da%a9%d8%b1%d8%af%d9%86-%d8%a8%d8%b1-%d8%a7%d8%b3%d8%a7%d8%b3-%d9%86%d8%a7%d9%85\">Suche nach Namen<\/h2>\n<p>Die naheliegendste Methode, Dateien zu suchen, ist die Suche nach ihrem Namen. Um eine Datei anhand ihres Namens zu finden, verwenden Sie den Befehl <code>finden<\/code>Sie sollten folgenden Befehl verwenden:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find -name \"query\"<\/code><\/pre>\n<\/div>\n<p>Hierbei wird zwischen Gro\u00df- und Kleinschreibung unterschieden, d. h. die Suche nach dem Suchbegriff entspricht der Suche nach <code>Abfrage<\/code> Das ist anders. Um eine Datei anhand ihres Namens zu finden, dabei aber die Gro\u00df-\/Kleinschreibung zu ignorieren, verwenden Sie die Option -iname:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find -iname \"query\"<\/code><\/pre>\n<\/div>\n<p>Wenn Sie alle Dateien finden m\u00f6chten, die keinem bestimmten Muster entsprechen, k\u00f6nnen Sie die Suche eingrenzen mit <code>-nicht <\/code>Umkehren:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find -not -name \"query_to_avoid\"<\/code><\/pre>\n<\/div>\n<p>Alternativ k\u00f6nnen Sie die Suche mit einem Ausrufezeichen (!) umkehren, so wie hier:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find \\! -name \"query_to_avoid\"<\/code><\/pre>\n<\/div>\n<p>Beachten Sie, dass Sie das Ausrufezeichen (!) vor der Verwendung mit einem Backslash (\\) maskieren m\u00fcssen. <code>finden<\/code> Die Shell versucht nicht, die Information zu interpretieren, wenn sie sie interpretieren kann.<\/p>\n<h2 id=\"%db%8c%d8%a7%d9%81%d8%aa%d9%86-%d8%a8%d8%b1-%d8%a7%d8%b3%d8%a7%d8%b3-%d9%86%d9%88%d8%b9\">Nach Typ suchen<\/h2>\n<p>Mit Parameter <code>-Typ<\/code> Sie k\u00f6nnen die Dateitypen angeben, die Sie finden m\u00f6chten. So funktioniert es:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find -type type_descriptor query<\/code><\/pre>\n<\/div>\n<p>Hier sind einige Beschreibungsmerkmale, anhand derer Sie den Dateityp bestimmen k\u00f6nnen:<\/p>\n<ul>\n<li>f: Normale Datei<\/li>\n<li>d: Verzeichnis<\/li>\n<li>l: symbolischer Link<\/li>\n<li>c: Zeichenger\u00e4te<\/li>\n<li>b: Blockiert Ger\u00e4te<\/li>\n<\/ul>\n<p>Wenn Sie beispielsweise alle Zeichenger\u00e4te auf Ihrem System finden m\u00f6chten, k\u00f6nnen Sie folgenden Befehl ausf\u00fchren:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find \/dev -type c<\/code><\/pre>\n<\/div>\n<p>Dieser Befehl sucht gezielt nur nach Ger\u00e4ten im Ordner \/dev, dem Verzeichnis, in dem Ger\u00e4tedateien typischerweise auf Linux-Systemen installiert werden:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>Output\r\n\/dev\/vcsa5\r\n\/dev\/vcsu5\r\n\/dev\/vcs5\r\n\/dev\/vcsa4\r\n\/dev\/vcsu4\r\n\/dev\/vcs4\r\n\/dev\/vcsa3\r\n\/dev\/vcsu3\r\n\/dev\/vcs3\r\n\/dev\/vcsa2\r\n\/dev\/vcsu2\r\n\/dev\/vcs2\r\n. . .<\/code><\/pre>\n<\/div>\n<p>Sie k\u00f6nnen alle Dateien anzeigen, die <code>.conf<\/code> Suche nach Dateien, die auf . enden. Dieses Beispiel findet passende Dateien im Ordner <code>\/usr <\/code>Suchanfragen:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find \/usr -type f -name \"*.conf\"<\/code><\/pre>\n<\/div>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>Output\r\n\/usr\/src\/linux-headers-5.4.0-88-generic\/include\/config\/auto.conf\r\n\/usr\/src\/linux-headers-5.4.0-88-generic\/include\/config\/tristate.conf\r\n\/usr\/src\/linux-headers-5.4.0-90-generic\/include\/config\/auto.conf\r\n\/usr\/src\/linux-headers-5.4.0-90-generic\/include\/config\/tristate.conf\r\n\/usr\/share\/adduser\/adduser.conf\r\n\/usr\/share\/ufw\/ufw.conf\r\n\/usr\/share\/popularity-contest\/default.conf\r\n\/usr\/share\/byobu\/keybindings\/tmux-screen-keys.conf\r\n\/usr\/share\/libc-bin\/nsswitch.conf\r\n\/usr\/share\/rsyslog\/50-default.conf\r\n. . .<\/code><\/pre>\n<\/div>\n<h2 id=\"%d9%81%db%8c%d9%84%d8%aa%d8%b1-%da%a9%d8%b1%d8%af%d9%86-%d8%a8%d8%b1-%d8%a7%d8%b3%d8%a7%d8%b3-%d8%b2%d9%85%d8%a7%d9%86-%d9%88-%d8%a7%d9%86%d8%af%d8%a7%d8%b2%d9%87\">Nach Zeit und Gr\u00f6\u00dfe filtern<\/h2>\n<p><code>finden<\/code> Es bietet Ihnen verschiedene M\u00f6glichkeiten, die Ergebnisse nach Gr\u00f6\u00dfe und Zeit zu filtern.<\/p>\n<h5 id=\"%d8%a7%d9%86%d8%af%d8%a7%d8%b2%d9%87\">Gr\u00f6\u00dfe<\/h5>\n<p>Verwendung des Parameters <code>-Gr\u00f6\u00dfe<\/code> Sie k\u00f6nnen Dateien nach ihrer Gr\u00f6\u00dfe filtern. Dazu m\u00fcssen Sie dem numerischen Gr\u00f6\u00dfenwert ein spezielles Suffix anh\u00e4ngen, um anzugeben, ob die Gr\u00f6\u00dfe in Byte, Megabyte, Gigabyte oder einer anderen Ma\u00dfeinheit angegeben wird. Hier sind einige g\u00e4ngige Gr\u00f6\u00dfensuffixe:<\/p>\n<ul>\n<li>c: Bytes<\/li>\n<li>k: Kilobyte<\/li>\n<li>m: Megabyte<\/li>\n<li>g: Gigabyte<\/li>\n<li>b: 512-Byte-Bl\u00f6cke<\/li>\n<\/ul>\n<p>Zur Veranschaulichung: Der folgende Befehl findet alle Dateien im Verzeichnis \/usr, die genau 50 Byte lang sind:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find \/usr -size 50c<\/code><\/pre>\n<\/div>\n<p>Um Dateien zu finden, die kleiner als 50 Byte sind, k\u00f6nnen Sie diese Syntax verwenden:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find \/usr -size -50c<\/code><\/pre>\n<\/div>\n<p>Um Dateien im Ordner \/usr zu finden, die gr\u00f6\u00dfer als 700 MB sind, k\u00f6nnen Sie folgenden Befehl verwenden:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find \/usr -size +700M<\/code><\/pre>\n<\/div>\n<h5 id=\"%d8%b2%d9%85%d8%a7%d9%86\">Zeit<\/h5>\n<p>F\u00fcr jede Datei im System speichert Linux Zeitstempel f\u00fcr Zugriffszeit, \u00c4nderungszeit und \u00c4nderungsdauer.<\/p>\n<ul>\n<li>Zugriffszeit: Der Zeitpunkt, zu dem eine Datei zuletzt gelesen oder geschrieben wurde.<\/li>\n<li>\u00c4nderungszeitpunkt: Der Zeitpunkt, zu dem der Inhalt der Datei zuletzt ge\u00e4ndert wurde.<\/li>\n<li>\u00c4nderungszeitpunkt: Der Zeitpunkt, zu dem die Inode-Metadaten der Datei zuletzt ge\u00e4ndert wurden.<\/li>\n<\/ul>\n<p>Die Optionen nutzen <code>Zeit-<\/code> ,<code>mtime-<\/code> Und <code>-ctime<\/code>Sie k\u00f6nnen Ihre Suchvorg\u00e4nge anhand dieser Parameter gestalten. F\u00fcr jede dieser Optionen m\u00fcssen Sie einen Wert angeben, der angibt, wie viele Tage in der Vergangenheit Sie suchen m\u00f6chten. \u00c4hnlich wie bei den zuvor beschriebenen Gr\u00f6\u00dfenoptionen k\u00f6nnen Sie diesen Optionen Plus- oder Minuszeichen voranstellen, um \u00abgr\u00f6\u00dfer als\u00bb oder \u00abkleiner als\u00bb anzugeben.<\/p>\n<p>Um beispielsweise Dateien im Ordner \/usr zu finden, die im Laufe des letzten Tages ge\u00e4ndert wurden, f\u00fchren Sie folgenden Befehl aus:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find \/usr -mtime 1<\/code><\/pre>\n<\/div>\n<p>Wenn Sie auf Dateien zugreifen m\u00f6chten, die Sie vor weniger als einem Tag aufgerufen haben, k\u00f6nnen Sie diesen Befehl ausf\u00fchren:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find \/usr -atime -1<\/code><\/pre>\n<\/div>\n<p>Um Dateien zu finden, deren Metadaten zuletzt vor mehr als 3 Tagen ge\u00e4ndert wurden, k\u00f6nnen Sie folgenden Befehl ausf\u00fchren:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find \/usr -ctime +3<\/code><\/pre>\n<\/div>\n<p>Diese Optionen verf\u00fcgen au\u00dferdem \u00fcber zugeh\u00f6rige Parameter, mit denen Sie Minuten anstelle von Tagen angeben k\u00f6nnen:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find \/usr -mmin -1<\/code><\/pre>\n<\/div>\n<p>Hier werden die Dateien angezeigt, die zuletzt ge\u00e4ndert wurden.<\/p>\n<p><code>finden<\/code> Es kann auch einen Vergleich mit einer Referenzdatei durchf\u00fchren und neuere Elemente zur\u00fcckgeben:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find \/ -newer reference_file<\/code><\/pre>\n<\/div>\n<p>Diese Syntax gibt alle Dateien im System zur\u00fcck, die vor kurzem relativ zur Referenzdatei erstellt oder ge\u00e4ndert wurden.<\/p>\n<h2 id=\"%db%8c%d8%a7%d9%81%d8%aa%d9%86-%d8%aa%d9%88%d8%b3%d8%b7-%d9%85%d8%a7%d9%84%da%a9-%d9%88-%d9%85%d8%ac%d9%88%d8%b2%d9%87%d8%a7\">Suche nach Eigent\u00fcmer und Berechtigungen<\/h2>\n<p>Sie k\u00f6nnen auch nach Dateien suchen, die dem Benutzer oder der Gruppe geh\u00f6ren, die die Datei besitzt. Verwenden Sie dazu die Parameter `-user` und `-group`. Um eine beliebige Datei im Verzeichnis `\/var` zu finden, die dem Benutzer `syslog` geh\u00f6rt, f\u00fchren Sie folgenden Befehl aus:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find \/var -user syslog<\/code><\/pre>\n<\/div>\n<p>Ebenso k\u00f6nnen Sie die Dateien im Verzeichnis \/etc, die zur Gruppe shadow geh\u00f6ren, auflisten, indem Sie Folgendes eingeben:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find \/etc -group shadow<\/code><\/pre>\n<\/div>\n<p>Sie k\u00f6nnen auch nach Dateien mit bestimmten Berechtigungen suchen.<\/p>\n<p>Wenn Sie eine exakte Berechtigungsliste abgleichen m\u00f6chten, k\u00f6nnen Sie diese Syntax verwenden, die Berechtigungen in Oktalschreibweise angibt:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find \/ -perm 644<\/code><\/pre>\n<\/div>\n<p>Dadurch werden Dateien mit exakt den angegebenen Berechtigungen abgeglichen.<\/p>\n<p>Wenn Sie etwas mit mindestens diesen Berechtigungen angeben m\u00f6chten, k\u00f6nnen Sie dem Berechtigungssymbol ein Minuszeichen voranstellen:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find \/ -perm -644<\/code><\/pre>\n<\/div>\n<p>Dies trifft auf alle Dateien mit zus\u00e4tzlichen Berechtigungen zu. In diesem Beispiel entspricht eine Datei mit den Berechtigungen 744 dieser Zuordnung.<\/p>\n<h2 id=\"%d9%81%db%8c%d9%84%d8%aa%d8%b1-%da%a9%d8%b1%d8%af%d9%86-%d8%a8%d8%b1-%d8%a7%d8%b3%d8%a7%d8%b3-%d8%b9%d9%85%d9%82\">Filtern nach Tiefe<\/h2>\n<p>In diesem Abschnitt erstellen Sie eine Beispielverzeichnisstruktur, anhand derer Sie anschlie\u00dfend das Filtern von Dateien basierend auf ihrer Verschachtelungstiefe untersuchen. Wenn Sie den Beispielen in diesem Tutorial folgen, empfiehlt es sich, diese Dateien und Verzeichnisse im Ordner `\/tmp\/` anzulegen. `\/tmp\/` ist ein tempor\u00e4res Verzeichnis. Das bedeutet, dass alle darin enthaltenen Dateien und Verzeichnisse beim n\u00e4chsten Serverstart gel\u00f6scht werden. Dies ist f\u00fcr diese Anleitung von Vorteil, da Sie beliebig viele Verzeichnisse, Dateien und Verkn\u00fcpfungen erstellen k\u00f6nnen, ohne bef\u00fcrchten zu m\u00fcssen, dass diese sp\u00e4ter Ihr System beeintr\u00e4chtigen. Nach Ausf\u00fchrung der Befehle in diesem Abschnitt enth\u00e4lt Ihr `\/tmp\/`-Verzeichnis drei Verzeichnisebenen, wobei die erste Ebene zehn Verzeichnisse enth\u00e4lt. Jedes Verzeichnis (einschlie\u00dflich des tempor\u00e4ren Verzeichnisses) enth\u00e4lt zehn Dateien und zehn Unterverzeichnisse.<\/p>\n<p>Erstellen Sie mit folgendem Befehl eine Beispielverzeichnisstruktur im Ordner \/tmp\/:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\">mkdir -p \/tmp\/test\/level1dir{1..10}\/level2dir{1..10}\/level3dir{1..10}<\/pre>\n<\/div>\n<p>Anschlie\u00dfend f\u00fcllen Sie diese Verzeichnisse mit einigen Beispieldateien mithilfe des Befehls \u201etouch\u201c:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>touch \/tmp\/test\/{file{1..10},level1dir{1..10}\/{file{1..10},level2dir{1..10}\/{file{1..10},level3dir{1..10}\/file{1..10}}}}<\/code><\/pre>\n<\/div>\n<p>Nachdem diese Dateien und Verzeichnisse vorhanden sind, wechseln Sie nun in das soeben erstellte Verzeichnis \u201etest\/\u201c:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>cd \/tmp\/test<\/code><\/pre>\n<\/div>\n<p>Um ein grundlegendes Verst\u00e4ndnis daf\u00fcr zu erlangen, wie man Dateien aus dieser Struktur abruft, beginnen Sie mit der Suche nach dem regul\u00e4ren Namen, der mit einer beliebigen Datei namens file1 \u00fcbereinstimmt:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find -name file1<\/code><\/pre>\n<\/div>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>Output\r\n.\/level1dir7\/level2dir8\/level3dir9\/file1\r\n.\/level1dir7\/level2dir8\/level3dir3\/file1\r\n.\/level1dir7\/level2dir8\/level3dir4\/file1\r\n.\/level1dir7\/level2dir8\/level3dir1\/file1\r\n.\/level1dir7\/level2dir8\/level3dir8\/file1\r\n.\/level1dir7\/level2dir8\/level3dir7\/file1\r\n.\/level1dir7\/level2dir8\/level3dir2\/file1\r\n.\/level1dir7\/level2dir8\/level3dir6\/file1\r\n.\/level1dir7\/level2dir8\/level3dir5\/file1\r\n.\/level1dir7\/level2dir8\/file1\r\n. . .<\/code><\/pre>\n<\/div>\n<p>Dies wird eine gro\u00dfe Anzahl von Ergebnissen liefern. Wenn Sie die Ausgabe in einen Z\u00e4hler einspeisen, werden Sie sehen, dass es insgesamt 1111 Ergebnisse gibt:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find -name file1 | wc -l<\/code><\/pre>\n<\/div>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>Output\r\n1111<\/code><\/pre>\n<\/div>\n<p>Dies sind wahrscheinlich zu viele Ergebnisse, um in den meisten Situationen hilfreich zu sein. Um die Anzahl zu begrenzen, k\u00f6nnen Sie in der obersten Suchliste eine maximale Suchtiefe festlegen:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find -maxdepth num -name query<\/code><\/pre>\n<\/div>\n<p>Um die Datei file1 nur in Verzeichnissen der Ebene 1 und h\u00f6her zu finden, k\u00f6nnen Sie eine maximale Tiefe von 2 angeben (1 f\u00fcr das oberste Verzeichnis und 1 f\u00fcr die Verzeichnisse der Ebene 1):<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find -maxdepth 2 -name file1<\/code><\/pre>\n<\/div>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>Output\r\n.\/level1dir7\/file1\r\n.\/level1dir1\/file1\r\n.\/level1dir3\/file1\r\n.\/level1dir8\/file1\r\n.\/level1dir6\/file1\r\n.\/file1\r\n.\/level1dir2\/file1\r\n.\/level1dir9\/file1\r\n.\/level1dir4\/file1\r\n.\/level1dir5\/file1\r\n.\/level1dir10\/file1<\/code><\/pre>\n<\/div>\n<p>Das ist eine sehr \u00fcberschaubare Liste.<\/p>\n<p>Sie k\u00f6nnen auch ein Mindestverzeichnis angeben, wenn Sie wissen, dass sich alle Dateien ab einem bestimmten Zeitpunkt unterhalb des aktuellen Verzeichnisses befinden:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find -mindepth num -name query<\/code><\/pre>\n<\/div>\n<p>Damit k\u00f6nnen Sie nur die Dateien am Ende von Verzeichniszweigen finden:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find -mindepth 4 -name file1<\/code><\/pre>\n<\/div>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>Output\r\n.\/level1dir7\/level2dir8\/level3dir9\/file1\r\n.\/level1dir7\/level2dir8\/level3dir3\/file1\r\n.\/level1dir7\/level2dir8\/level3dir4\/file1\r\n.\/level1dir7\/level2dir8\/level3dir1\/file1\r\n.\/level1dir7\/level2dir8\/level3dir8\/file1\r\n.\/level1dir7\/level2dir8\/level3dir7\/file1\r\n.\/level1dir7\/level2dir8\/level3dir2\/file1\r\n. . .<\/code><\/pre>\n<\/div>\n<\/div>\n<p>Auch hier werden aufgrund der Branch-and-File-Struktur 1000 Ergebnisse zur\u00fcckgegeben.<\/p>\n<p>Sie k\u00f6nnen die Parameter f\u00fcr minimale und maximale Tiefe kombinieren, um sich auf einen engen Bereich zu konzentrieren:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find -mindepth 2 -maxdepth 3 -name file1<\/code><\/pre>\n<\/div>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>Output\r\n.\/level1dir7\/level2dir8\/file1\r\n.\/level1dir7\/level2dir5\/file1\r\n.\/level1dir7\/level2dir7\/file1\r\n.\/level1dir7\/level2dir2\/file1\r\n.\/level1dir7\/level2dir10\/file1\r\n.\/level1dir7\/level2dir6\/file1\r\n.\/level1dir7\/level2dir3\/file1\r\n.\/level1dir7\/level2dir4\/file1\r\n.\/level1dir7\/file1\r\n. . .<\/code><\/pre>\n<\/div>\n<p>Durch die Kombination dieser Optionen wird die Anzahl der Ergebnisse deutlich reduziert; es werden nur noch 110 Zeilen anstelle der vorherigen 1000 Zeilen zur\u00fcckgegeben.<\/p>\n<h2 id=\"%d8%a7%d8%ac%d8%b1%d8%a7%db%8c-%d8%af%d8%b3%d8%aa%d9%88%d8%b1%d8%a7%d8%aa-%d8%af%d8%b1-%db%8c%d8%a7%d9%81%d8%aa%d9%86-%d9%86%d8%aa%d8%a7%db%8c%d8%ac\">Befehle ausf\u00fchren, um Ergebnisse zu finden<\/h2>\n<p>Sie k\u00f6nnen den Parameter verwenden <code>-exec <\/code>F\u00fchren Sie einen benutzerdefinierten Hilfsbefehl f\u00fcr alle \u00fcbereinstimmenden Elemente mit folgendem Befehl aus:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find find_parameters -exec command_and_options {} \\;<\/code><\/pre>\n<\/div>\n<p>{} dient als Platzhalter f\u00fcr \u00fcbereinstimmende Dateien. \\; zeigt an, wo der Befehl endet.<\/p>\n<p>Angenommen, Sie befinden sich noch im Verzeichnis \/test\/, das Sie im vorherigen Schritt im Ordner \/tmp\/ erstellt haben, k\u00f6nnen Sie die Dateien aus dem vorherigen Abschnitt, die die Berechtigungen 644 hatten, finden und sie so \u00e4ndern, dass sie die Berechtigungen 664 haben:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find . -type f -perm 644 -exec chmod 664 {} \\;<\/code><\/pre>\n<\/div>\n<p>Sie k\u00f6nnen auch die Verzeichnisberechtigungen auf \u00e4hnliche Weise \u00e4ndern:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>find . -type d -perm 755 -exec chmod 700 {} \\;<\/code><\/pre>\n<\/div>\n<p>Dieses Beispiel findet alle Verzeichnisse, deren Berechtigungen auf 755 gesetzt sind, und \u00e4ndert dann die Berechtigungen auf 700.<\/p>\n<h2 id=\"%db%8c%d8%a7%d9%81%d8%aa%d9%86-%d9%81%d8%a7%db%8c%d9%84-%d9%87%d8%a7-%d8%a8%d8%a7-%d8%a7%d8%b3%d8%aa%d9%81%d8%a7%d8%af%d9%87-%d8%a7%d8%b2-locate\">Dateien mit der Funktion &quot;Locate&quot; finden<\/h2>\n<p>Alternative zur Verwendung <code>finden<\/code> Befehl <code>lokalisieren<\/code> Dieser Befehl ist oft schneller und kann das gesamte Dateisystem problemlos durchsuchen.<\/p>\n<p>Sie k\u00f6nnen den Befehl in Debian oder Ubuntu mit apt installieren, indem Sie Ihre Paketliste aktualisieren und anschlie\u00dfend das Paket molocate installieren:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\">sudo apt update\r\nsudo apt install mlocate<\/pre>\n<\/div>\n<p>Unter Rocky Linux, CentOS und anderen von RedHat abgeleiteten Distributionen k\u00f6nnen Sie mlocate mit dem Befehl dnf installieren:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>sudo dnf install mlocate<\/code><\/pre>\n<\/div>\n<p>Der Grund, warum `locate` schneller als `find` ist, liegt darin, dass es auf einer Datenbank basiert, die alle Dateien im Dateisystem auflistet. Diese Datenbank wird \u00fcblicherweise einmal t\u00e4glich per Cron-Skript aktualisiert, kann aber auch manuell mit dem Befehl `updatedb` aktualisiert werden. F\u00fchren Sie nun folgenden Befehl mit sudo-Rechten aus:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>sudo updatedb<\/code><\/pre>\n<\/div>\n<p>Denken Sie daran: Um neue Dateien zu finden, muss die Standortdatenbank stets aktuell sein. Wenn Sie neue Dateien hinzuf\u00fcgen, bevor das Cron-Skript oder der Befehl `updatedb` ausgef\u00fchrt wird, werden diese nicht in den Suchergebnissen angezeigt.<\/p>\n<p>Der Standort erm\u00f6glicht es Ihnen, Ergebnisse auf verschiedene Weise zu filtern. Die einfachste Methode zum Auffinden von Dateien ist die Verwendung dieser Syntax:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>locate query<\/code><\/pre>\n<\/div>\n<p>Dies findet alle Dateien und Verzeichnisse, deren Dateipfad die Zeichenkette \u00abquery\u00bb enth\u00e4lt. Um nur Dateien zur\u00fcckzugeben, deren Namen die Zeichenkette \u201equery\u201c selbst enthalten, anstatt aller Dateien, die die Zeichenkette \u201equery\u201c in den \u00fcbergeordneten Verzeichnissen enthalten, k\u00f6nnen Sie den Parameter \u201e-b\u201c hinzuf\u00fcgen, um nur Dateien zu durchsuchen, deren \u201eBasisname\u201c mit der Zeichenkette \u201equery\u201c \u00fcbereinstimmt.<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>locate -b query<\/code><\/pre>\n<\/div>\n<p>Um sicherzustellen, dass `locate` nur Ergebnisse zur\u00fcckgibt, die noch im Dateisystem vorhanden sind (d. h. Dateien, die zwischen dem letzten Aufruf von `updatedb` und dem aktuellen Aufruf von `locate` nicht gel\u00f6scht wurden), verwenden Sie `-e:`<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>locate -e query<\/code><\/pre>\n<\/div>\n<p>Sie k\u00f6nnen Statistiken zu den Informationen abrufen, in denen der Standort aufgef\u00fchrt ist, indem Sie die Option -S verwenden:<\/p>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>locate -S<\/code><\/pre>\n<\/div>\n<div class=\"hcb_wrap\" data-no-translation=\"\" data-no-auto-translation=\"\">\n<pre class=\"prism line-numbers lang-bash\" data-lang=\"Bash\"><code>Output\r\nDatabase \/var\/lib\/mlocate\/mlocate.db:\r\n21015 directories\r\n136787 files\r\n7727763 bytes in file names\r\n3264413 bytes used to store database<\/code><\/pre>\n<\/div>\n<p>Dies kann hilfreich sein, um sich einen guten \u00dcberblick \u00fcber die Anzahl der Dateien und Verzeichnisse auf Ihrem System zu verschaffen.<\/p>\n<h2 id=\"%d9%86%d8%aa%db%8c%d8%ac%d9%87\">Ergebnis<\/h2>\n<p>Sowohl `find` als auch `locate` sind n\u00fctzliche Werkzeuge zum Auffinden von Dateien auf Ihrem System. Beide sind leistungsstarke Befehle, die sich durch die Kombination mit anderen Werkzeugen in Pipelines erweitern lassen. Sie entscheiden, welches Werkzeug f\u00fcr Ihre Bed\u00fcrfnisse am besten geeignet ist. Wir empfehlen Ihnen, weiter mit `find` und `locate` zu experimentieren. In den jeweiligen Manpages finden Sie weitere Optionen, die in diesem Leitfaden nicht behandelt werden. Sie k\u00f6nnen die Suchergebnisse analysieren und bearbeiten, indem Sie sie an andere Befehle wie `wc`, `sort` und `grep` \u00fcbergeben.<\/p>","protected":false},"excerpt":{"rendered":"Einleitung Eines der Probleme, auf die Benutzer beim Erlernen des Umgangs mit Linux sto\u00dfen, ist\u2026","protected":false},"author":1,"featured_media":14682,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_wpseo_focuskw":"\u062c\u0633\u062a\u062c\u0648\u06cc \u0641\u0627\u06cc\u0644 \u062f\u0631 \u0644\u06cc\u0646\u0648\u06a9\u0633","_yoast_wpseo_title":"","_yoast_wpseo_metadesc":"","_yoast_wpseo_canonical":"","_yoast_wpseo_opengraph-description":"","_yoast_wpseo_opengraph-image":"","_yoast_wpseo_twitter-description":"","_yoast_wpseo_twitter-image":"","_yoast_wpseo_focuskeywords":"","_yoast_wpseo_primary_category":"193","footnotes":""},"categories":[193,349],"tags":[356],"class_list":{"0":"post-14681","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tutorials","8":"category-database","9":"tag-356"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0646\u062d\u0648\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 Find and Locate \u0628\u0631\u0627\u06cc \u062c\u0633\u062a\u062c\u0648\u06cc \u0641\u0627\u06cc\u0644 \u0647\u0627 \u062f\u0631 \u0644\u06cc\u0646\u0648\u06a9\u0633 - \u0628\u0644\u0627\u06af ITPiran<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itpiran.net\/blog\/de\/tutorials\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0646\u062d\u0648\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 Find and Locate \u0628\u0631\u0627\u06cc \u062c\u0633\u062a\u062c\u0648\u06cc \u0641\u0627\u06cc\u0644 \u0647\u0627 \u062f\u0631 \u0644\u06cc\u0646\u0648\u06a9\u0633 - \u0628\u0644\u0627\u06af ITPiran\" \/>\n<meta property=\"og:description\" content=\"\u0645\u0642\u062f\u0645\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0634\u06a9\u0644\u0627\u062a\u06cc \u06a9\u0647 \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u062f\u0631 \u0627\u0648\u0644\u06cc\u0646 \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0646\u062d\u0648\u0647 \u06a9\u0627\u0631 \u0628\u0627 \u0644\u06cc\u0646\u0648\u06a9\u0633 \u0628\u0627 \u0622\u0646 \u0645\u0648\u0627\u062c\u0647 \u0645\u06cc \u0634\u0648\u0646\u062f&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itpiran.net\/blog\/de\/tutorials\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0628\u0644\u0627\u06af ITPiran\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-04T07:49:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-04T09:29:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.itpiran.net\/2024\/02\/04111803\/Linux-BackG.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1793\" \/>\n\t<meta property=\"og:image:height\" content=\"1110\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/tutorials\\\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/tutorials\\\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/#\\\/schema\\\/person\\\/04ed27b919baca468a2273f8e4318f81\"},\"headline\":\"\u0646\u062d\u0648\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 Find and Locate \u0628\u0631\u0627\u06cc \u062c\u0633\u062a\u062c\u0648\u06cc \u0641\u0627\u06cc\u0644 \u0647\u0627 \u062f\u0631 \u0644\u06cc\u0646\u0648\u06a9\u0633\",\"datePublished\":\"2024-02-04T07:49:44+00:00\",\"dateModified\":\"2024-02-04T09:29:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/tutorials\\\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\\\/\"},\"wordCount\":60,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/tutorials\\\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.itpiran.net\\\/2024\\\/02\\\/04111803\\\/Linux-BackG.jpg\",\"keywords\":[\"\u0644\u06cc\u0646\u0648\u06a9\u0633\"],\"articleSection\":[\"\u0622\u0645\u0648\u0632\u0634\u06cc\",\"\u067e\u0627\u06cc\u06af\u0627\u0647 \u062f\u0627\u062f\u0647\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/tutorials\\\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/tutorials\\\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\\\/\",\"url\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/tutorials\\\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\\\/\",\"name\":\"\u0646\u062d\u0648\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 Find and Locate \u0628\u0631\u0627\u06cc \u062c\u0633\u062a\u062c\u0648\u06cc \u0641\u0627\u06cc\u0644 \u0647\u0627 \u062f\u0631 \u0644\u06cc\u0646\u0648\u06a9\u0633 - \u0628\u0644\u0627\u06af ITPiran\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/tutorials\\\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/tutorials\\\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.itpiran.net\\\/2024\\\/02\\\/04111803\\\/Linux-BackG.jpg\",\"datePublished\":\"2024-02-04T07:49:44+00:00\",\"dateModified\":\"2024-02-04T09:29:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/tutorials\\\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/tutorials\\\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/tutorials\\\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.itpiran.net\\\/2024\\\/02\\\/04111803\\\/Linux-BackG.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.itpiran.net\\\/2024\\\/02\\\/04111803\\\/Linux-BackG.jpg\",\"width\":1793,\"height\":1110},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/tutorials\\\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0622\u0645\u0648\u0632\u0634\u06cc\",\"item\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/category\\\/tutorials\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0646\u062d\u0648\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 Find and Locate \u0628\u0631\u0627\u06cc \u062c\u0633\u062a\u062c\u0648\u06cc \u0641\u0627\u06cc\u0644 \u0647\u0627 \u062f\u0631 \u0644\u06cc\u0646\u0648\u06a9\u0633\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/\",\"name\":\"\u0628\u0644\u0627\u06af ITPiran\",\"description\":\"\u0627\u062e\u0628\u0627\u0631 \u0648 \u0645\u0642\u0627\u0644\u0627\u062a \u062a\u062c\u0627\u0631\u062a \u067e\u0627\u06cc\u062f\u0627\u0631 \u0627\u06cc\u0631\u0627\u0646\u06cc\u0627\u0646\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/#organization\",\"name\":\"\u0628\u0644\u0627\u06af \u062a\u062c\u0627\u0631\u062a \u067e\u0627\u06cc\u062f\u0627\u0631 \u0627\u06cc\u0631\u0627\u0646\u06cc\u0627\u0646\",\"alternateName\":\"ITPIran Blog\",\"url\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdn.itpiran.net\\\/2023\\\/12\\\/27150508\\\/cropped-ITPIRAN-BLOG-LOGO-2.png\",\"contentUrl\":\"https:\\\/\\\/cdn.itpiran.net\\\/2023\\\/12\\\/27150508\\\/cropped-ITPIRAN-BLOG-LOGO-2.png\",\"width\":512,\"height\":512,\"caption\":\"\u0628\u0644\u0627\u06af \u062a\u062c\u0627\u0631\u062a \u067e\u0627\u06cc\u062f\u0627\u0631 \u0627\u06cc\u0631\u0627\u0646\u06cc\u0627\u0646\"},\"image\":{\"@id\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/#\\\/schema\\\/person\\\/04ed27b919baca468a2273f8e4318f81\",\"name\":\"admin\",\"url\":\"https:\\\/\\\/www.itpiran.net\\\/blog\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wie man unter Linux mit \u201eSuchen\u201c und \u201eLokalisieren\u201c nach Dateien sucht \u2013 ITPiran-Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itpiran.net\/blog\/de\/tutorials\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\/","og_locale":"de_DE","og_type":"article","og_title":"\u0646\u062d\u0648\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 Find and Locate \u0628\u0631\u0627\u06cc \u062c\u0633\u062a\u062c\u0648\u06cc \u0641\u0627\u06cc\u0644 \u0647\u0627 \u062f\u0631 \u0644\u06cc\u0646\u0648\u06a9\u0633 - \u0628\u0644\u0627\u06af ITPiran","og_description":"\u0645\u0642\u062f\u0645\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0634\u06a9\u0644\u0627\u062a\u06cc \u06a9\u0647 \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u062f\u0631 \u0627\u0648\u0644\u06cc\u0646 \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0646\u062d\u0648\u0647 \u06a9\u0627\u0631 \u0628\u0627 \u0644\u06cc\u0646\u0648\u06a9\u0633 \u0628\u0627 \u0622\u0646 \u0645\u0648\u0627\u062c\u0647 \u0645\u06cc \u0634\u0648\u0646\u062f&hellip;","og_url":"https:\/\/www.itpiran.net\/blog\/de\/tutorials\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\/","og_site_name":"\u0628\u0644\u0627\u06af ITPiran","article_published_time":"2024-02-04T07:49:44+00:00","article_modified_time":"2024-02-04T09:29:18+00:00","og_image":[{"width":1793,"height":1110,"url":"https:\/\/cdn.itpiran.net\/2024\/02\/04111803\/Linux-BackG.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.itpiran.net\/blog\/tutorials\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\/#article","isPartOf":{"@id":"https:\/\/www.itpiran.net\/blog\/tutorials\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\/"},"author":{"name":"admin","@id":"https:\/\/www.itpiran.net\/blog\/#\/schema\/person\/04ed27b919baca468a2273f8e4318f81"},"headline":"\u0646\u062d\u0648\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 Find and Locate \u0628\u0631\u0627\u06cc \u062c\u0633\u062a\u062c\u0648\u06cc \u0641\u0627\u06cc\u0644 \u0647\u0627 \u062f\u0631 \u0644\u06cc\u0646\u0648\u06a9\u0633","datePublished":"2024-02-04T07:49:44+00:00","dateModified":"2024-02-04T09:29:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.itpiran.net\/blog\/tutorials\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\/"},"wordCount":60,"commentCount":0,"publisher":{"@id":"https:\/\/www.itpiran.net\/blog\/#organization"},"image":{"@id":"https:\/\/www.itpiran.net\/blog\/tutorials\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.itpiran.net\/2024\/02\/04111803\/Linux-BackG.jpg","keywords":["\u0644\u06cc\u0646\u0648\u06a9\u0633"],"articleSection":["\u0622\u0645\u0648\u0632\u0634\u06cc","\u067e\u0627\u06cc\u06af\u0627\u0647 \u062f\u0627\u062f\u0647"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.itpiran.net\/blog\/tutorials\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.itpiran.net\/blog\/tutorials\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\/","url":"https:\/\/www.itpiran.net\/blog\/tutorials\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\/","name":"Wie man unter Linux mit \u201eSuchen\u201c und \u201eLokalisieren\u201c nach Dateien sucht \u2013 ITPiran-Blog","isPartOf":{"@id":"https:\/\/www.itpiran.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.itpiran.net\/blog\/tutorials\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\/#primaryimage"},"image":{"@id":"https:\/\/www.itpiran.net\/blog\/tutorials\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.itpiran.net\/2024\/02\/04111803\/Linux-BackG.jpg","datePublished":"2024-02-04T07:49:44+00:00","dateModified":"2024-02-04T09:29:18+00:00","breadcrumb":{"@id":"https:\/\/www.itpiran.net\/blog\/tutorials\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itpiran.net\/blog\/tutorials\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.itpiran.net\/blog\/tutorials\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\/#primaryimage","url":"https:\/\/cdn.itpiran.net\/2024\/02\/04111803\/Linux-BackG.jpg","contentUrl":"https:\/\/cdn.itpiran.net\/2024\/02\/04111803\/Linux-BackG.jpg","width":1793,"height":1110},{"@type":"BreadcrumbList","@id":"https:\/\/www.itpiran.net\/blog\/tutorials\/how-to-use-find-and-locate-to-search-for-files-on-linuxsize\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.itpiran.net\/blog\/"},{"@type":"ListItem","position":2,"name":"\u0622\u0645\u0648\u0632\u0634\u06cc","item":"https:\/\/www.itpiran.net\/blog\/category\/tutorials\/"},{"@type":"ListItem","position":3,"name":"\u0646\u062d\u0648\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 Find and Locate \u0628\u0631\u0627\u06cc \u062c\u0633\u062a\u062c\u0648\u06cc \u0641\u0627\u06cc\u0644 \u0647\u0627 \u062f\u0631 \u0644\u06cc\u0646\u0648\u06a9\u0633"}]},{"@type":"WebSite","@id":"https:\/\/www.itpiran.net\/blog\/#website","url":"https:\/\/www.itpiran.net\/blog\/","name":"ITPiran Blog","description":"Iranische Nachrichten und Artikel zum Thema nachhaltiger Handel","publisher":{"@id":"https:\/\/www.itpiran.net\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itpiran.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.itpiran.net\/blog\/#organization","name":"Nachhaltiger iranischer Unternehmensblog","alternateName":"ITPIran Blog","url":"https:\/\/www.itpiran.net\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.itpiran.net\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/cdn.itpiran.net\/2023\/12\/27150508\/cropped-ITPIRAN-BLOG-LOGO-2.png","contentUrl":"https:\/\/cdn.itpiran.net\/2023\/12\/27150508\/cropped-ITPIRAN-BLOG-LOGO-2.png","width":512,"height":512,"caption":"\u0628\u0644\u0627\u06af \u062a\u062c\u0627\u0631\u062a \u067e\u0627\u06cc\u062f\u0627\u0631 \u0627\u06cc\u0631\u0627\u0646\u06cc\u0627\u0646"},"image":{"@id":"https:\/\/www.itpiran.net\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.itpiran.net\/blog\/#\/schema\/person\/04ed27b919baca468a2273f8e4318f81","name":"Administrator","url":"https:\/\/www.itpiran.net\/blog\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.itpiran.net\/blog\/de\/wp-json\/wp\/v2\/posts\/14681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itpiran.net\/blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.itpiran.net\/blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.itpiran.net\/blog\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.itpiran.net\/blog\/de\/wp-json\/wp\/v2\/comments?post=14681"}],"version-history":[{"count":1,"href":"https:\/\/www.itpiran.net\/blog\/de\/wp-json\/wp\/v2\/posts\/14681\/revisions"}],"predecessor-version":[{"id":14683,"href":"https:\/\/www.itpiran.net\/blog\/de\/wp-json\/wp\/v2\/posts\/14681\/revisions\/14683"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.itpiran.net\/blog\/de\/wp-json\/wp\/v2\/media\/14682"}],"wp:attachment":[{"href":"https:\/\/www.itpiran.net\/blog\/de\/wp-json\/wp\/v2\/media?parent=14681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.itpiran.net\/blog\/de\/wp-json\/wp\/v2\/categories?post=14681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.itpiran.net\/blog\/de\/wp-json\/wp\/v2\/tags?post=14681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}